{"id":9208,"date":"2025-02-26T17:54:22","date_gmt":"2025-02-26T21:54:22","guid":{"rendered":"https:\/\/indeedinsurance.net\/?page_id=9208"},"modified":"2025-12-16T16:27:57","modified_gmt":"2025-12-16T20:27:57","slug":"terminos-y-condiciones-sms","status":"publish","type":"page","link":"https:\/\/indeedinsurance.net\/en\/terminos-y-condiciones-sms\/","title":{"rendered":"T\u00e9rminos y Condiciones SMS | Indeed Insurance"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"9208\" class=\"elementor elementor-9208\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-4382122 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4382122\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8058504\" data-id=\"8058504\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b57e6c color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"4b57e6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1><span class=\"elementor-icon-list-text\">Privacy policy<\/span> SMS<\/h1><p>Uso de mensajes SMS<\/p><p>Indeed insurance Corp.\u00a0se encargar\u00e1 de enviar\u00a0mensajes a los clientes dando informaci\u00f3n sobre su cobertura general, los pagos a sus p\u00f3lizas de seguro, detalles de cobertura, informaci\u00f3n sobre requerimientos de documentos por las compa\u00f1\u00edas o mercados federales de salud y otros. Y cualquier informaci\u00f3n de cotizaci\u00f3n relacionada con coberturas de p\u00f3lizas de cualquier tipo e informaci\u00f3n de finanzas relacionadas con anualidades, p\u00f3lizas de vida entre otros.<\/p><p>Usted puede cancelar el servicio de SMS en cualquier momento. Simplemente mand\u00e9 un mensaje de texto &#8220;STOP&#8221;. Despu\u00e9s que mande el mensaje de texto &#8220;STOP&#8221; a nosotros, le mandaremos un mensaje SMS para confirmar que se ha dado de baja. Despu\u00e9s de esto, ya no va a recibir m\u00e1s mensajes SMS de nosotros. Si quiere suscribirse de nuevo solo h\u00e1galo de nuevo como la primera vez y vamos a mandarme mensajes SMS otra vez.<\/p><p>Si est\u00e1 experimentando problemas con el programa de mensajer\u00eda, puede responder con la palabra Ayuda para asistencia, o puede pedir ayuda a este correo electr\u00f3nico contacto@indeedinsurance.net o n\u00famero de tel\u00e9fono 786-6848794.<\/p><p>Como es Sabido, Cargos por mensajer\u00eda y datos pueden aplicar por mensajes enviados a usted y de usted a nosotros. Va a recibir mensajes cada 2 d\u00edas a la semana. Si tiene m\u00e1s preguntas acerca su plan de SMS o plan de datos, es mayor contactar a su compa\u00f1\u00eda de telefon\u00eda celular.<\/p><p>Si tiene preguntas en relaci\u00f3n a pol\u00edticas de privacidad, por favor leer nuestra\u00a0pol\u00edtica de privacidad.<\/p><h2>Pol\u00edticas de Privacidad<\/h2><p>Uso de SMS<\/p><p>Colecci\u00f3n de datos: Se obtendr\u00e1 su nombre, correo electr\u00f3nico, direcci\u00f3n y n\u00famero de tel\u00e9fono m\u00f3vil cuando se subscriba para mensajes SMS<\/p><p>Uso de datos: Usamos sus datos \u00fanicamente para enviar actualizaciones, promociones y recordatorios relacionados a nuestros productos y servicios.<\/p><p>Seguridad de Datos: Nuestros protegemos sus datos con medidas altas de seguridad para prevenir acceso no autorizado.<\/p><p>Retenci\u00f3n de Datos: Nosotros retenemos su informaci\u00f3n mientras est\u00e9 suscrito para mensajer\u00eda SMS. Puede solicitar eliminar su informaci\u00f3n en cualquier momento.<\/p><p>CARGOS POR MENSAJER\u00cdA Y DATA PUEDEN APLICAR: Su proveedor de telefon\u00eda celular puede hacer cobros por mandar o recibir mensajes SMS, especialmente si no tiene un plan ilimitado de mensajes de texto o datos.<\/p><p>Mensajes son recurrentes y la frecuencia puede variar.<\/p><p>Contacto: INDEED INSURANCE CORP: 786-6848794\u00a0y contacto@indeedinsurance.net para AYUDA o STOP para parar de recibir mensajes.<\/p><p>OPT-OUT: puede cancelar la suscripci\u00f3n de SMS en cualquier momento mandado por texto la palabra STOP. Despu\u00e9s de cancelar la subscripci\u00f3n ya no va a recibir m\u00e1s mensajes de texto.<\/p><p>Puede mandar la palabra AYUDA para asistencia adicional, va a recibir un mensaje de texto con nuestro n\u00famero de tel\u00e9fono, email o p\u00e1gina web. Estamos para ayudarle.<\/p><p>Clausula de No compartir informaci\u00f3n: Nosotros no compartimos su data con compa\u00f1\u00edas terceras para prop\u00f3sitos de marketing. INDEED INSURANCE CORP no vendemos, rentanos o compartimos los n\u00fameros de tel\u00e9fono colectados.\u00a0786-6848794.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de Privacidad SMS Uso de mensajes SMS Indeed insurance Corp.\u00a0se encargar\u00e1 de enviar\u00a0mensajes a los clientes dando informaci\u00f3n sobre<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"nf_dc_page":"","_joinchat":[],"footnotes":""},"class_list":["post-9208","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Conoce los t\u00e9rminos y condiciones del servicio de mensajer\u00eda SMS de Indeed Insurance. Informaci\u00f3n sobre uso, consentimiento y privacidad.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"ntNyZSvCpUilEvjAv-vZZrYgiUMazn74CBAOrPWhdXU\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/indeedinsurance.net\/en\/terminos-y-condiciones-sms\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Indeed Insurance -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"T\u00e9rminos y Condiciones SMS | Indeed Insurance\" \/>\n\t\t<meta property=\"og:description\" content=\"Conoce los t\u00e9rminos y condiciones del servicio de mensajer\u00eda SMS de Indeed Insurance. Informaci\u00f3n sobre uso, consentimiento y privacidad.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/indeedinsurance.net\/en\/terminos-y-condiciones-sms\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-02-26T21:54:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-12-16T20:27:57+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"T\u00e9rminos y Condiciones SMS | Indeed Insurance\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Conoce los t\u00e9rminos y condiciones del servicio de mensajer\u00eda SMS de Indeed Insurance. Informaci\u00f3n sobre uso, consentimiento y privacidad.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/indeedinsurance.net\\\/en\\\/terminos-y-condiciones-sms\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/indeedinsurance.net\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/indeedinsurance.net\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/indeedinsurance.net\\\/en\\\/terminos-y-condiciones-sms\\\/#listItem\",\"name\":\"T\\u00e9rminos y Condiciones SMS | Indeed Insurance\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/indeedinsurance.net\\\/en\\\/terminos-y-condiciones-sms\\\/#listItem\",\"position\":2,\"name\":\"T\\u00e9rminos y Condiciones SMS | Indeed Insurance\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/indeedinsurance.net\\\/en#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/indeedinsurance.net\\\/en\\\/#organization\",\"name\":\"Indeed Insurance\",\"url\":\"https:\\\/\\\/indeedinsurance.net\\\/en\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/indeedinsurance.net\\\/en\\\/terminos-y-condiciones-sms\\\/#webpage\",\"url\":\"https:\\\/\\\/indeedinsurance.net\\\/en\\\/terminos-y-condiciones-sms\\\/\",\"name\":\"T\\u00e9rminos y Condiciones SMS | Indeed Insurance\",\"description\":\"Conoce los t\\u00e9rminos y condiciones del servicio de mensajer\\u00eda SMS de Indeed Insurance. Informaci\\u00f3n sobre uso, consentimiento y privacidad.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/indeedinsurance.net\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/indeedinsurance.net\\\/en\\\/terminos-y-condiciones-sms\\\/#breadcrumblist\"},\"datePublished\":\"2025-02-26T17:54:22-04:00\",\"dateModified\":\"2025-12-16T16:27:57-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/indeedinsurance.net\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/indeedinsurance.net\\\/en\\\/\",\"name\":\"Indeed Insurance\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/indeedinsurance.net\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"T\u00e9rminos y Condiciones SMS | Indeed Insurance","description":"Conoce los t\u00e9rminos y condiciones del servicio de mensajer\u00eda SMS de Indeed Insurance. Informaci\u00f3n sobre uso, consentimiento y privacidad.","canonical_url":"https:\/\/indeedinsurance.net\/en\/terminos-y-condiciones-sms\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"ntNyZSvCpUilEvjAv-vZZrYgiUMazn74CBAOrPWhdXU","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/indeedinsurance.net\/en\/terminos-y-condiciones-sms\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/indeedinsurance.net\/en#listItem","position":1,"name":"Home","item":"https:\/\/indeedinsurance.net\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/indeedinsurance.net\/en\/terminos-y-condiciones-sms\/#listItem","name":"T\u00e9rminos y Condiciones SMS | Indeed Insurance"}},{"@type":"ListItem","@id":"https:\/\/indeedinsurance.net\/en\/terminos-y-condiciones-sms\/#listItem","position":2,"name":"T\u00e9rminos y Condiciones SMS | Indeed Insurance","previousItem":{"@type":"ListItem","@id":"https:\/\/indeedinsurance.net\/en#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/indeedinsurance.net\/en\/#organization","name":"Indeed Insurance","url":"https:\/\/indeedinsurance.net\/en\/"},{"@type":"WebPage","@id":"https:\/\/indeedinsurance.net\/en\/terminos-y-condiciones-sms\/#webpage","url":"https:\/\/indeedinsurance.net\/en\/terminos-y-condiciones-sms\/","name":"T\u00e9rminos y Condiciones SMS | Indeed Insurance","description":"Conoce los t\u00e9rminos y condiciones del servicio de mensajer\u00eda SMS de Indeed Insurance. Informaci\u00f3n sobre uso, consentimiento y privacidad.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/indeedinsurance.net\/en\/#website"},"breadcrumb":{"@id":"https:\/\/indeedinsurance.net\/en\/terminos-y-condiciones-sms\/#breadcrumblist"},"datePublished":"2025-02-26T17:54:22-04:00","dateModified":"2025-12-16T16:27:57-04:00"},{"@type":"WebSite","@id":"https:\/\/indeedinsurance.net\/en\/#website","url":"https:\/\/indeedinsurance.net\/en\/","name":"Indeed Insurance","inLanguage":"en-US","publisher":{"@id":"https:\/\/indeedinsurance.net\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Indeed Insurance -","og:type":"article","og:title":"T\u00e9rminos y Condiciones SMS | Indeed Insurance","og:description":"Conoce los t\u00e9rminos y condiciones del servicio de mensajer\u00eda SMS de Indeed Insurance. Informaci\u00f3n sobre uso, consentimiento y privacidad.","og:url":"https:\/\/indeedinsurance.net\/en\/terminos-y-condiciones-sms\/","article:published_time":"2025-02-26T21:54:22+00:00","article:modified_time":"2025-12-16T20:27:57+00:00","twitter:card":"summary_large_image","twitter:title":"T\u00e9rminos y Condiciones SMS | Indeed Insurance","twitter:description":"Conoce los t\u00e9rminos y condiciones del servicio de mensajer\u00eda SMS de Indeed Insurance. Informaci\u00f3n sobre uso, consentimiento y privacidad."},"aioseo_meta_data":{"post_id":"9208","title":"T\u00e9rminos y Condiciones SMS | Indeed Insurance","description":"Conoce los t\u00e9rminos y condiciones del servicio de mensajer\u00eda SMS de Indeed Insurance. Informaci\u00f3n sobre uso, consentimiento y privacidad.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-12-16 19:37:45","updated":"2025-12-16 20:48:35","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/indeedinsurance.net\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tT\u00e9rminos y Condiciones SMS | Indeed Insurance\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/indeedinsurance.net\/en"},{"label":"T\u00e9rminos y Condiciones SMS | Indeed Insurance","link":"https:\/\/indeedinsurance.net\/en\/terminos-y-condiciones-sms\/"}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/indeedinsurance.net\/en\/wp-json\/wp\/v2\/pages\/9208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indeedinsurance.net\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/indeedinsurance.net\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/indeedinsurance.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/indeedinsurance.net\/en\/wp-json\/wp\/v2\/comments?post=9208"}],"version-history":[{"count":5,"href":"https:\/\/indeedinsurance.net\/en\/wp-json\/wp\/v2\/pages\/9208\/revisions"}],"predecessor-version":[{"id":9253,"href":"https:\/\/indeedinsurance.net\/en\/wp-json\/wp\/v2\/pages\/9208\/revisions\/9253"}],"wp:attachment":[{"href":"https:\/\/indeedinsurance.net\/en\/wp-json\/wp\/v2\/media?parent=9208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}